{"id":305,"date":"2023-09-20T18:51:56","date_gmt":"2023-09-20T16:51:56","guid":{"rendered":"https:\/\/alainlonguet.com\/?page_id=305"},"modified":"2023-10-26T18:52:31","modified_gmt":"2023-10-26T16:52:31","slug":"generatif","status":"publish","type":"page","link":"https:\/\/alainlonguet.com\/index.php\/generatif\/","title":{"rendered":"G\u00e9n\u00e9ratif"},"content":{"rendered":"<style>.kb-row-layout-id305_b1e43b-60 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id305_b1e43b-60 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id305_b1e43b-60 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id305_b1e43b-60 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id305_b1e43b-60 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id305_b1e43b-60 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id305_b1e43b-60 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id305_b1e43b-60 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id305_b1e43b-60 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id305_b1e43b-60 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id305_b1e43b-60 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column305_9a3e0c-92 > .kt-inside-inner-col,.kadence-column305_9a3e0c-92 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column305_9a3e0c-92 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column305_9a3e0c-92 > .kt-inside-inner-col{flex-direction:column;}.kadence-column305_9a3e0c-92 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column305_9a3e0c-92 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column305_9a3e0c-92{position:relative;}@media all and (max-width: 1024px){.kadence-column305_9a3e0c-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column305_9a3e0c-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column305_9a3e0c-92\"><div class=\"kt-inside-inner-col\"><style>.kb-image305_f5816f-0a.kb-image-is-ratio-size, .kb-image305_f5816f-0a .kb-image-is-ratio-size{max-width:294px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image305_f5816f-0a.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image305_f5816f-0a .kb-image-is-ratio-size{align-self:unset;}.kb-image305_f5816f-0a{max-width:294px;}.image-is-svg.kb-image305_f5816f-0a{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image305_f5816f-0a img{width:100%;}.kb-image305_f5816f-0a .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image305_f5816f-0a\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/alainlonguet.com\/wp-content\/uploads\/2023\/10\/imotif_foursquares.jpg\" alt=\"\" class=\"kb-img wp-image-369\" srcset=\"https:\/\/alainlonguet.com\/wp-content\/uploads\/2023\/10\/imotif_foursquares.jpg 300w, https:\/\/alainlonguet.com\/wp-content\/uploads\/2023\/10\/imotif_foursquares-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column305_3fc105-8b > .kt-inside-inner-col{display:flex;}.kadence-column305_3fc105-8b > .kt-inside-inner-col,.kadence-column305_3fc105-8b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column305_3fc105-8b > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column305_3fc105-8b > .kt-inside-inner-col > *, .kadence-column305_3fc105-8b > .kt-inside-inner-col > figure.wp-block-image, .kadence-column305_3fc105-8b > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column305_3fc105-8b > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column305_3fc105-8b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column305_3fc105-8b{position:relative;}@media all and (max-width: 1024px){.kadence-column305_3fc105-8b > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column305_3fc105-8b > .kt-inside-inner-col > *, .kadence-column305_3fc105-8b > .kt-inside-inner-col > figure.wp-block-image, .kadence-column305_3fc105-8b > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column305_3fc105-8b > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column305_3fc105-8b > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column305_3fc105-8b > .kt-inside-inner-col > *, .kadence-column305_3fc105-8b > .kt-inside-inner-col > figure.wp-block-image, .kadence-column305_3fc105-8b > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column305_3fc105-8b > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column305_3fc105-8b kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\">\n<p><a href=\"http:\/\/alainlonguet.free.fr\/processing\/FourSquaresMultiplyInMotion.html\" target=\"_blank\" rel=\"noreferrer noopener\">Four squares in motion \/2021<\/a><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column305_805b59-6b > .kt-inside-inner-col,.kadence-column305_805b59-6b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column305_805b59-6b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column305_805b59-6b > .kt-inside-inner-col{flex-direction:column;}.kadence-column305_805b59-6b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column305_805b59-6b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column305_805b59-6b{position:relative;}@media all and (max-width: 1024px){.kadence-column305_805b59-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column305_805b59-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column305_805b59-6b\"><div class=\"kt-inside-inner-col\"><style>.kb-image305_3add97-5f.kb-image-is-ratio-size, .kb-image305_3add97-5f .kb-image-is-ratio-size{max-width:295px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image305_3add97-5f.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image305_3add97-5f .kb-image-is-ratio-size{align-self:unset;}.kb-image305_3add97-5f{max-width:295px;}.image-is-svg.kb-image305_3add97-5f{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image305_3add97-5f img{width:100%;}.kb-image305_3add97-5f .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image305_3add97-5f size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/alainlonguet.com\/wp-content\/uploads\/2023\/10\/imotif_faisceaux.jpg\" alt=\"\" class=\"kb-img wp-image-370\" srcset=\"https:\/\/alainlonguet.com\/wp-content\/uploads\/2023\/10\/imotif_faisceaux.jpg 300w, https:\/\/alainlonguet.com\/wp-content\/uploads\/2023\/10\/imotif_faisceaux-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column305_4ac7b6-30 > .kt-inside-inner-col,.kadence-column305_4ac7b6-30 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column305_4ac7b6-30 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column305_4ac7b6-30 > .kt-inside-inner-col{flex-direction:column;}.kadence-column305_4ac7b6-30 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column305_4ac7b6-30 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column305_4ac7b6-30{position:relative;}@media all and (max-width: 1024px){.kadence-column305_4ac7b6-30 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column305_4ac7b6-30 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column305_4ac7b6-30\"><div class=\"kt-inside-inner-col\">\n<p><a href=\"http:\/\/alainlonguet.free.fr\/processing\/faisceaux.html\" target=\"_blank\" rel=\"noreferrer noopener\">Faisceaux \/2021<\/a><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id305_356eaf-d7 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id305_356eaf-d7 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id305_356eaf-d7 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id305_356eaf-d7 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id305_356eaf-d7 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id305_356eaf-d7 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id305_356eaf-d7 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id305_356eaf-d7 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id305_356eaf-d7 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id305_356eaf-d7 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id305_356eaf-d7 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column305_78d5e3-9c > .kt-inside-inner-col,.kadence-column305_78d5e3-9c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column305_78d5e3-9c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column305_78d5e3-9c > .kt-inside-inner-col{flex-direction:column;}.kadence-column305_78d5e3-9c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column305_78d5e3-9c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column305_78d5e3-9c{position:relative;}@media all and (max-width: 1024px){.kadence-column305_78d5e3-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column305_78d5e3-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column305_78d5e3-9c\"><div class=\"kt-inside-inner-col\"><style>.kb-image305_24508b-2f.kb-image-is-ratio-size, .kb-image305_24508b-2f .kb-image-is-ratio-size{max-width:294px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image305_24508b-2f.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image305_24508b-2f .kb-image-is-ratio-size{align-self:unset;}.kb-image305_24508b-2f{max-width:294px;}.image-is-svg.kb-image305_24508b-2f{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image305_24508b-2f img{width:100%;}.kb-image305_24508b-2f .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image305_24508b-2f size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/alainlonguet.com\/wp-content\/uploads\/2023\/10\/imotif_skybubbles.jpg\" alt=\"\" class=\"kb-img wp-image-371\" srcset=\"https:\/\/alainlonguet.com\/wp-content\/uploads\/2023\/10\/imotif_skybubbles.jpg 300w, https:\/\/alainlonguet.com\/wp-content\/uploads\/2023\/10\/imotif_skybubbles-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column305_7c8b7b-7f > .kt-inside-inner-col{display:flex;}.kadence-column305_7c8b7b-7f > .kt-inside-inner-col,.kadence-column305_7c8b7b-7f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column305_7c8b7b-7f > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column305_7c8b7b-7f > .kt-inside-inner-col > *, .kadence-column305_7c8b7b-7f > .kt-inside-inner-col > figure.wp-block-image, .kadence-column305_7c8b7b-7f > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column305_7c8b7b-7f > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column305_7c8b7b-7f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column305_7c8b7b-7f{position:relative;}@media all and (max-width: 1024px){.kadence-column305_7c8b7b-7f > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column305_7c8b7b-7f > .kt-inside-inner-col > *, .kadence-column305_7c8b7b-7f > .kt-inside-inner-col > figure.wp-block-image, .kadence-column305_7c8b7b-7f > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column305_7c8b7b-7f > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column305_7c8b7b-7f > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column305_7c8b7b-7f > .kt-inside-inner-col > *, .kadence-column305_7c8b7b-7f > .kt-inside-inner-col > figure.wp-block-image, .kadence-column305_7c8b7b-7f > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column305_7c8b7b-7f > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column305_7c8b7b-7f kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\">\n<p><a href=\"http:\/\/alainlonguet.free.fr\/processing\/skybubbles.html\" target=\"_blank\" rel=\"noreferrer noopener\">Skybubbles \/2019<\/a><\/p>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column305_563818-59 > .kt-inside-inner-col,.kadence-column305_563818-59 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column305_563818-59 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column305_563818-59 > .kt-inside-inner-col{flex-direction:column;}.kadence-column305_563818-59 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column305_563818-59 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column305_563818-59{position:relative;}@media all and (max-width: 1024px){.kadence-column305_563818-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column305_563818-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column305_563818-59\"><div class=\"kt-inside-inner-col\"><style>.kb-image305_70cada-9f.kb-image-is-ratio-size, .kb-image305_70cada-9f .kb-image-is-ratio-size{max-width:295px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image305_70cada-9f.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image305_70cada-9f .kb-image-is-ratio-size{align-self:unset;}.kb-image305_70cada-9f{max-width:295px;}.image-is-svg.kb-image305_70cada-9f{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image305_70cada-9f img{width:100%;}.kb-image305_70cada-9f .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image305_70cada-9f\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/alainlonguet.com\/wp-content\/uploads\/2023\/10\/Links.jpg\" alt=\"\" class=\"kb-img wp-image-372\" srcset=\"https:\/\/alainlonguet.com\/wp-content\/uploads\/2023\/10\/Links.jpg 800w, https:\/\/alainlonguet.com\/wp-content\/uploads\/2023\/10\/Links-300x300.jpg 300w, https:\/\/alainlonguet.com\/wp-content\/uploads\/2023\/10\/Links-150x150.jpg 150w, https:\/\/alainlonguet.com\/wp-content\/uploads\/2023\/10\/Links-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column305_85410c-ca > .kt-inside-inner-col,.kadence-column305_85410c-ca > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column305_85410c-ca > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column305_85410c-ca > .kt-inside-inner-col{flex-direction:column;}.kadence-column305_85410c-ca > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column305_85410c-ca > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column305_85410c-ca{position:relative;}@media all and (max-width: 1024px){.kadence-column305_85410c-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column305_85410c-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column305_85410c-ca\"><div class=\"kt-inside-inner-col\">\n<p><a href=\"http:\/\/alainlonguet.free.fr\/processing\/Links.html\">L<\/a><a href=\"http:\/\/alainlonguet.free.fr\/processing\/Links.html\" target=\"_blank\" rel=\"noreferrer noopener\">inks \/199<\/a><a href=\"http:\/\/alainlonguet.free.fr\/processing\/Links.html\">5<\/a><\/p>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Four squares in motion \/2021 Faisceaux \/2021 Skybubbles \/2019 Links \/1995<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-305","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/alainlonguet.com\/index.php\/wp-json\/wp\/v2\/pages\/305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alainlonguet.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alainlonguet.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alainlonguet.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alainlonguet.com\/index.php\/wp-json\/wp\/v2\/comments?post=305"}],"version-history":[{"count":10,"href":"https:\/\/alainlonguet.com\/index.php\/wp-json\/wp\/v2\/pages\/305\/revisions"}],"predecessor-version":[{"id":444,"href":"https:\/\/alainlonguet.com\/index.php\/wp-json\/wp\/v2\/pages\/305\/revisions\/444"}],"wp:attachment":[{"href":"https:\/\/alainlonguet.com\/index.php\/wp-json\/wp\/v2\/media?parent=305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}